{"id":451,"date":"2022-03-14T20:26:04","date_gmt":"2022-03-14T20:26:04","guid":{"rendered":"https:\/\/www.cirugiaparatodos.com.mx\/blog\/?p=451"},"modified":"2024-09-30T18:02:22","modified_gmt":"2024-09-30T18:02:22","slug":"como-se-relaciona-el-covid-19-y-la-tiroides","status":"publish","type":"post","link":"https:\/\/www.cirugiaparatodos.com.mx\/blog\/como-se-relaciona-el-covid-19-y-la-tiroides\/","title":{"rendered":"\u00bfC\u00f3mo se relaciona el Covid-19 y la Tiroides?"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">Estamos cumpliendo 2 a\u00f1os desde que se reportaron los primeros casos de covid-19, y en todo este tiempo hemos podido aprender m\u00e1s sobre esta enfermedad causada por el virus <\/span><span style=\"color: #00ccff;\"><b>SARS-CoV-2<\/b><\/span><span style=\"font-weight: 400;\"> y los estragos que causa en nuestro cuerpo.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Aunque las v\u00edas respiratorias y el pulm\u00f3n son sus objetivos principales, este virus tiene la capacidad de afectar muchos otros \u00f3rganos y sistemas de forma simult\u00e1nea.<\/span><\/p>\n<p><!--more--><\/p>\n<p><span style=\"font-weight: 400;\">Se han documentado afecciones en el <\/span><span style=\"color: #00ccff;\"><b>sistema nervioso central<\/b><\/span><span style=\"font-weight: 400;\">, ojos, coraz\u00f3n, h\u00edgado, p\u00e1ncreas, tracto gastrointestinal, ri\u00f1ones, piel, arterias y m\u00e1s. La <\/span><span style=\"color: #00ccff;\"><b>gl\u00e1ndula tiroides<\/b><\/span><span style=\"font-weight: 400;\"> es otra de estas v\u00edctimas y en muchos casos lastimosamente\u00a0 pasa desapercibida.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">La <\/span><span style=\"color: #00ccff;\"><b>tiroides<\/b><\/span><span style=\"font-weight: 400;\"> produce hormonas, siendo la <\/span><span style=\"color: #00ccff;\"><b>T3 y T4\u00a0 las m\u00e1s importantes<\/b><\/span><span style=\"font-weight: 400;\">. Estas hormonas son liberadas al torrente sangu\u00edneo en cantidades necesarias seg\u00fan nuestros requerimientos corporales y llegan a la mayor\u00eda de c\u00e9lulas en nuestro cuerpo, en do<\/span><span style=\"font-weight: 400;\">nde tienen la funci\u00f3n vital de regular la <\/span><span style=\"color: #00ccff;\"><b>velocidad del metabolismo<\/b><\/span><span style=\"font-weight: 400;\"> en cada una de ellas.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">En condiciones <\/span><span style=\"color: #00ccff;\"><b>patol\u00f3gicas<\/b><\/span><span style=\"font-weight: 400;\"> podemos vernos expuestos a un <\/span><span style=\"color: #00ccff;\"><b>exceso<\/b><\/span><span style=\"font-weight: 400;\"> o un <\/span><span style=\"color: #00ccff;\"><b>d\u00e9ficit<\/b><\/span><span style=\"font-weight: 400;\"> de estas <\/span><span style=\"color: #00ccff;\"><b>hormonas<\/b><\/span><span style=\"font-weight: 400;\"> y ambos escenarios son perjudiciales para la salud.<\/span><\/p>\n<h2><b>\u00bfCu\u00e1l es la relaci\u00f3n entre la COVID-19 y la Tiroides?<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">Los pacientes que padecen alguna<\/span><span style=\"color: #00ccff;\"><b> enfermedad tiroidea pueden ser m\u00e1s vulnerables a los efectos del virus <\/b><\/span><span style=\"font-weight: 400;\">y <\/span><span style=\"color: #00ccff;\"><b>sufrir m\u00e1s complicaciones cuando tienen covid-19.<\/b><\/span><span style=\"font-weight: 400;\"> En estudios publicados durante noviembre del 2021, se concluy\u00f3 que los pacientes con <\/span><span style=\"color: #00ccff;\"><b>hipotiroidismo<\/b><\/span><span style=\"font-weight: 400;\"> o que presentaban <\/span><span style=\"color: #00ccff;\"><b>pruebas<\/b> <b>tiroideas<\/b> <b>alteradas<\/b><\/span><span style=\"font-weight: 400;\"> ten\u00edan un mayor riesgo de <\/span><span style=\"color: #00ccff;\"><b>cursar con COVID-19 grave<\/b><\/span><span style=\"font-weight: 400;\"><span style=\"color: #00ccff;\">,<\/span> requerir atenci\u00f3n en cuidados paliativos y morir como consecuencia de esta enfermedad.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">El <\/span><i><span style=\"font-weight: 400;\">Dr. Luca Giovanella <\/span><\/i><span style=\"font-weight: 400;\">y un equipo de m\u00e9dicos analizaron datos reportados en varias partes del mundo, evidenciando que entre un 14% y un 64% de los pacientes enfermos por <\/span><span style=\"color: #00ccff;\"><b>COVID-19<\/b><\/span><span style=\"font-weight: 400;\"> puede presentar alteraci\u00f3n de estas hormonas, quiz\u00e1 como da\u00f1o directo sobre la gl\u00e1ndula, afecci\u00f3n del eje central que la regula o como producto de la respuesta inmune del cuerpo.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">La <\/span><span style=\"color: #00ccff;\"><b>COVID-19<\/b><\/span><span style=\"font-weight: 400;\"> puede tambi\u00e9n desatar una<\/span><span style=\"color: #00ccff;\"><b> enfermedad tiroidea<\/b><\/span><span style=\"font-weight: 400;\"> que se presente semanas o meses despu\u00e9s de la fase aguda, conocida como <\/span><span style=\"color: #00ccff;\"><b>tiroiditis de Quervain o tiroiditis subaguda<\/b><\/span><span style=\"font-weight: 400;\"><span style=\"color: #00ccff;\">.<\/span>\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Tambi\u00e9n te puede interesar: <\/span><a href=\"https:\/\/www.cirugiaparatodos.com.mx\/blog\/que-comprende-la-cirugia-de-cabeza-y-cuello\/\"><span style=\"font-weight: 400;\">\u00bfQu\u00e9 comprende la cirug\u00eda de cabeza y cuello?<\/span><\/a><\/p>\n<p><span style=\"font-weight: 400;\">Esta enfermedad se relaciona con <\/span><span style=\"color: #00ccff;\"><b>infecciones virales<\/b><\/span><span style=\"font-weight: 400;\"><span style=\"color: #00ccff;\">,<\/span> (no es exclusiva del SARS-CoV-2) y se compone por un episodio transitorio de inflamaci\u00f3n de la gl\u00e1ndula y liberaci\u00f3n en grandes cantidades de sus hormonas.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Los pacientes pueden presentar dolor en el cuello, cansancio, fatiga, malestar general, palpitaciones, taquicardia o fiebre. Aunque suele ser autolimitada y en la mayor\u00eda de casos no es fatal.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Es importante saber identificarla, ya que al confundirse con otros diagn\u00f3sticos, podemos incurrir en gastos innecesarios, tratamientos inadecuados y estr\u00e9s excesivo en el o la paciente y su familia.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Mantener las medidas de <\/span><span style=\"color: #00ccff;\"><b>bioseguridad<\/b><\/span><span style=\"font-weight: 400;\">, vacunarnos y consultar de forma oportuna a tu especialista,\u00a0 son las mejores herramientas para evitar la relaci\u00f3n da\u00f1ina entre este virus y nuestra gl\u00e1ndula tiroides.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Estamos cumpliendo 2 a\u00f1os desde que se reportaron los primeros casos de covid-19, y en todo este tiempo hemos podido aprender m\u00e1s sobre esta enfermedad causada por el virus SARS-CoV-2 y los estragos que causa en nuestro cuerpo. Aunque las v\u00edas respiratorias y el pulm\u00f3n son sus objetivos principales, este virus tiene la capacidad de &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/www.cirugiaparatodos.com.mx\/blog\/como-se-relaciona-el-covid-19-y-la-tiroides\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00ab\u00bfC\u00f3mo se relaciona el Covid-19 y la Tiroides?\u00bb<\/span><\/a><\/p>\n","protected":false},"author":4,"featured_media":455,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[130],"tags":[22,4,56,87,106,76,126,7,26,129,128,123,90,108,10,124,125,27,6,70,127],"_links":{"self":[{"href":"https:\/\/www.cirugiaparatodos.com.mx\/blog\/wp-json\/wp\/v2\/posts\/451"}],"collection":[{"href":"https:\/\/www.cirugiaparatodos.com.mx\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cirugiaparatodos.com.mx\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cirugiaparatodos.com.mx\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cirugiaparatodos.com.mx\/blog\/wp-json\/wp\/v2\/comments?post=451"}],"version-history":[{"count":2,"href":"https:\/\/www.cirugiaparatodos.com.mx\/blog\/wp-json\/wp\/v2\/posts\/451\/revisions"}],"predecessor-version":[{"id":454,"href":"https:\/\/www.cirugiaparatodos.com.mx\/blog\/wp-json\/wp\/v2\/posts\/451\/revisions\/454"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cirugiaparatodos.com.mx\/blog\/wp-json\/wp\/v2\/media\/455"}],"wp:attachment":[{"href":"https:\/\/www.cirugiaparatodos.com.mx\/blog\/wp-json\/wp\/v2\/media?parent=451"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cirugiaparatodos.com.mx\/blog\/wp-json\/wp\/v2\/categories?post=451"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cirugiaparatodos.com.mx\/blog\/wp-json\/wp\/v2\/tags?post=451"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}